{"id":7261,"date":"2023-06-30T11:09:41","date_gmt":"2023-06-30T11:09:41","guid":{"rendered":"https:\/\/khanlowcostparking.com\/adress-alc\/"},"modified":"2023-07-19T08:00:19","modified_gmt":"2023-07-19T08:00:19","slug":"adress-alc","status":"publish","type":"page","link":"https:\/\/khanlowcostparking.com\/en\/adress-alc\/","title":{"rendered":"Adress ALC"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;2_3,1_3&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;2_3&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;]<iframe src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d3131.6587177079095!2d-0.5923819235444387!3d38.28740337186072!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0xd624ba542d291ff%3A0xed1ad577b5ae4586!2sKhan%20Alicante%20Low%20Cost%20Parking!5e0!3m2!1snl!2snl!4v1689691599426!5m2!1snl!2snl\" width=\"600\" height=\"450\" style=\"border: 0;\" allowfullscreen=\"\" loading=\"lazy\" referrerpolicy=\"no-referrer-when-downgrade\"><\/iframe>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font_size=&#8221;15px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4><strong>Khan Low Cost Parking &#8211; Airport Alicante<\/strong><\/h4>\n<p><span>+34 656183468<\/span><\/p>\n<p><span>alicante@khanlowcostparking.com<\/span><\/p>\n<p data-pm-slice=\"1 1 []\"><span>Partida Torrellano Alto, 1069, 03320 Elche, Alicante<\/span><\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/khanlowcostparking.com\/wp-content\/uploads\/2023\/06\/Schermafbeelding-2023-06-28-om-12.08.49.png&#8221; title_text=&#8221;Khan Low Cost Parking&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Khan Low Cost Parking &#8211; Airport Alicante +34 656183468 alicante@khanlowcostparking.com Partida Torrellano Alto, 1069, 03320 Elche, Alicante<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","_monsterinsights_skip_tracking":false,"footnotes":""},"class_list":["post-7261","page","type-page","status-publish","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/khanlowcostparking.com\/en\/wp-json\/wp\/v2\/pages\/7261","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/khanlowcostparking.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/khanlowcostparking.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/khanlowcostparking.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/khanlowcostparking.com\/en\/wp-json\/wp\/v2\/comments?post=7261"}],"version-history":[{"count":3,"href":"https:\/\/khanlowcostparking.com\/en\/wp-json\/wp\/v2\/pages\/7261\/revisions"}],"predecessor-version":[{"id":7945,"href":"https:\/\/khanlowcostparking.com\/en\/wp-json\/wp\/v2\/pages\/7261\/revisions\/7945"}],"wp:attachment":[{"href":"https:\/\/khanlowcostparking.com\/en\/wp-json\/wp\/v2\/media?parent=7261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}